{"id":21104,"date":"2024-02-09T09:50:05","date_gmt":"2024-02-09T07:50:05","guid":{"rendered":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14.jpg"},"modified":"2024-02-09T09:50:05","modified_gmt":"2024-02-09T07:50:05","slug":"business-escape-challenge-14-2","status":"inherit","type":"attachment","link":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/","title":{"rendered":"Business Escape Challenge (14)"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0},"class_list":["post-21104","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"American Academy\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"American Academy\"\/>\n\t<meta name=\"google-site-verification\" content=\"1GBqZ9YhyEObwKVlJAz6t3iyq0TUQlYqLJq8PYiTPKE\" \/>\n\t<meta name=\"msvalidate.01\" content=\"0D6AFA9A4E16BE096B4C1467E7612150\" \/>\n\t<meta name=\"yandex-verification\" content=\"f1e4b306a7b5a60d\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"ru_RU\" \/>\n\t\t<meta property=\"og:site_name\" content=\"American Academy \u2022 (Private) School Limassol\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Business Escape Challenge (14) | American Academy\" \/>\n\t\t<meta property=\"og:description\" content=\"American Academy\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/09\/Logo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/09\/Logo.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"752\" \/>\n\t\t<meta property=\"og:image:height\" content=\"813\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-09T07:50:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-09T07:50:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/American-Academy-Athletic-School-107035131005337\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/business-escape-challenge\\\/business-escape-challenge-14-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/business-escape-challenge\\\/business-escape-challenge-14-2\\\/#listItem\",\"name\":\"Business Escape Challenge (14)\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/business-escape-challenge\\\/business-escape-challenge-14-2\\\/#listItem\",\"position\":2,\"name\":\"Business Escape Challenge (14)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/business-escape-challenge\\\/business-escape-challenge-14-2\\\/#itempage\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/business-escape-challenge\\\/business-escape-challenge-14-2\\\/\",\"name\":\"Business Escape Challenge (14) | American Academy\",\"description\":\"American Academy\",\"inLanguage\":\"ru-RU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/business-escape-challenge\\\/business-escape-challenge-14-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/author\\\/amac\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/author\\\/amac\\\/#author\"},\"datePublished\":\"2024-02-09T09:50:05+02:00\",\"dateModified\":\"2024-02-09T09:50:05+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/#organization\",\"name\":\"American Academy Limassol\",\"description\":\"(Private) School Limassol\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/\",\"telephone\":\"+35725337054\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.jpg\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/business-escape-challenge\\\/business-escape-challenge-14-2\\\/#organizationLogo\",\"width\":752,\"height\":813,\"caption\":\"American Academy Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/business-escape-challenge\\\/business-escape-challenge-14-2\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/American-Academy-Athletic-School-107035131005337\",\"https:\\\/\\\/www.instagram.com\\\/americanacademyprivate\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgEJukzLPVITvwtccVN0N3w\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/american-academy-school\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/author\\\/amac\\\/#author\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/author\\\/amac\\\/\",\"name\":\"American Academy\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/\",\"name\":\"American Academy Limassol\",\"description\":\"(Private) School Limassol\",\"inLanguage\":\"ru-RU\",\"publisher\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/ru\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Business Escape Challenge (14) | American Academy","description":"American Academy","canonical_url":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"1GBqZ9YhyEObwKVlJAz6t3iyq0TUQlYqLJq8PYiTPKE","msvalidate.01":"0D6AFA9A4E16BE096B4C1467E7612150","yandex-verification":"f1e4b306a7b5a60d","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/ru\/#listItem","position":1,"name":"Home","item":"https:\/\/americanacademy.ac.cy\/ru\/","nextItem":{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/#listItem","name":"Business Escape Challenge (14)"}},{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/#listItem","position":2,"name":"Business Escape Challenge (14)","previousItem":{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/ru\/#listItem","name":"Home"}}]},{"@type":"ItemPage","@id":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/#itempage","url":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/","name":"Business Escape Challenge (14) | American Academy","description":"American Academy","inLanguage":"ru-RU","isPartOf":{"@id":"https:\/\/americanacademy.ac.cy\/ru\/#website"},"breadcrumb":{"@id":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/#breadcrumblist"},"author":{"@id":"https:\/\/americanacademy.ac.cy\/ru\/author\/amac\/#author"},"creator":{"@id":"https:\/\/americanacademy.ac.cy\/ru\/author\/amac\/#author"},"datePublished":"2024-02-09T09:50:05+02:00","dateModified":"2024-02-09T09:50:05+02:00"},{"@type":"Organization","@id":"https:\/\/americanacademy.ac.cy\/ru\/#organization","name":"American Academy Limassol","description":"(Private) School Limassol","url":"https:\/\/americanacademy.ac.cy\/ru\/","telephone":"+35725337054","logo":{"@type":"ImageObject","url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/01\/Logo.jpg","@id":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/#organizationLogo","width":752,"height":813,"caption":"American Academy Logo"},"image":{"@id":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/American-Academy-Athletic-School-107035131005337","https:\/\/www.instagram.com\/americanacademyprivate\/","https:\/\/www.youtube.com\/channel\/UCgEJukzLPVITvwtccVN0N3w","https:\/\/www.linkedin.com\/company\/american-academy-school\/"]},{"@type":"Person","@id":"https:\/\/americanacademy.ac.cy\/ru\/author\/amac\/#author","url":"https:\/\/americanacademy.ac.cy\/ru\/author\/amac\/","name":"American Academy"},{"@type":"WebSite","@id":"https:\/\/americanacademy.ac.cy\/ru\/#website","url":"https:\/\/americanacademy.ac.cy\/ru\/","name":"American Academy Limassol","description":"(Private) School Limassol","inLanguage":"ru-RU","publisher":{"@id":"https:\/\/americanacademy.ac.cy\/ru\/#organization"}}]},"og:locale":"ru_RU","og:site_name":"American Academy \u2022 (Private) School Limassol","og:type":"article","og:title":"Business Escape Challenge (14) | American Academy","og:description":"American Academy","og:url":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/","og:image":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/09\/Logo.jpg","og:image:secure_url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/09\/Logo.jpg","og:image:width":752,"og:image:height":813,"article:published_time":"2024-02-09T07:50:05+00:00","article:modified_time":"2024-02-09T07:50:05+00:00","article:publisher":"https:\/\/www.facebook.com\/American-Academy-Athletic-School-107035131005337"},"aioseo_meta_data":{"post_id":"21104","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-02-09 07:57:28","updated":"2025-06-06 20:09:50","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/americanacademy.ac.cy\/ru\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBusiness Escape Challenge (14)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/americanacademy.ac.cy\/ru\/"},{"label":"Business Escape Challenge (14)","link":"https:\/\/americanacademy.ac.cy\/ru\/business-escape-challenge\/business-escape-challenge-14-2\/"}],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"135\" src=\"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14-300x135.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14-300x135.jpg 300w, https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14-760x343.jpg 760w, https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14-768x346.jpg 768w, https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14.jpg 1420w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1420,"height":640,"file":"2024\/02\/Business-Escape-Challenge-14.jpg","filesize":60844,"sizes":{"medium":{"file":"Business-Escape-Challenge-14-300x135.jpg","width":300,"height":135,"filesize":8003,"mime_type":"image\/jpeg","source_url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14-300x135.jpg"},"large":{"file":"Business-Escape-Challenge-14-760x343.jpg","width":760,"height":343,"filesize":31744,"mime_type":"image\/jpeg","source_url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14-760x343.jpg"},"thumbnail":{"file":"Business-Escape-Challenge-14-150x150.jpg","width":150,"height":150,"filesize":4632,"mime_type":"image\/jpeg","source_url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14-150x150.jpg"},"medium_large":{"file":"Business-Escape-Challenge-14-768x346.jpg","width":768,"height":346,"filesize":32671,"mime_type":"image\/jpeg","source_url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14-768x346.jpg"},"cmplz_banner_image":{"file":"Business-Escape-Challenge-14-350x100.jpg","width":350,"height":100,"filesize":6461,"mime_type":"image\/jpeg","source_url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14-350x100.jpg"},"sow-carousel-default":{"file":"Business-Escape-Challenge-14-272x182.jpg","width":272,"height":182,"filesize":8892,"mime_type":"image\/jpeg","source_url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14-272x182.jpg"},"full":{"file":"Business-Escape-Challenge-14.jpg","width":1420,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":21062,"source_url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2024\/02\/Business-Escape-Challenge-14.jpg","filename":"Business-Escape-Challenge-14.jpg","filesize":60844,"_links":{"self":[{"href":"https:\/\/americanacademy.ac.cy\/ru\/wp-json\/wp\/v2\/media\/21104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/americanacademy.ac.cy\/ru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/americanacademy.ac.cy\/ru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/americanacademy.ac.cy\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/americanacademy.ac.cy\/ru\/wp-json\/wp\/v2\/comments?post=21104"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":21062,"href":"https:\/\/americanacademy.ac.cy\/ru\/wp-json\/wp\/v2\/posts\/21062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}