{"id":32977,"date":"2025-01-28T20:59:30","date_gmt":"2025-01-28T18:59:30","guid":{"rendered":"https:\/\/americanacademy.ac.cy\/donate-blood-safe-a-life\/"},"modified":"2025-01-28T21:02:07","modified_gmt":"2025-01-28T19:02:07","slug":"donate-blood-safe-a-life","status":"publish","type":"post","link":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/","title":{"rendered":"Donate blood &#8211; safe a life"},"content":{"rendered":"<div id=\"pl-32977\"  class=\"panel-layout\" ><div id=\"pg-32977-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-32977-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-32977-0-0-0\" class=\"so-panel widget widget_media_image panel-first-child\" data-index=\"0\" ><img loading=\"lazy\" decoding=\"async\" width=\"1448\" height=\"2048\" src=\"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2025\/01\/Donate-blood.jpg\" class=\"image wp-image-32980  attachment-full size-full\" alt=\"donate blood\" style=\"max-width: 100%; height: auto;\" srcset=\"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2025\/01\/Donate-blood.jpg 1448w, https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2025\/01\/Donate-blood-212x300.jpg 212w, https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2025\/01\/Donate-blood-537x760.jpg 537w, https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2025\/01\/Donate-blood-768x1086.jpg 768w, https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2025\/01\/Donate-blood-1086x1536.jpg 1086w\" sizes=\"auto, (max-width: 1448px) 100vw, 1448px\" \/><\/div><div id=\"panel-32977-0-0-1\" class=\"so-panel widget widget_text\" data-index=\"1\" >\t\t\t<div class=\"textwidget\"><p>Contact us<\/p>\n<div class=\"forminator-ui forminator-custom-form forminator-custom-form-9544 forminator-design--default  forminator_ajax\" data-forminator-render=\"0\" data-form=\"forminator-module-9544\" data-uid=\"6a576d082ce20\"><br\/><\/div><form\n\t\t\t\tid=\"forminator-module-9544\"\n\t\t\t\tclass=\"forminator-ui forminator-custom-form forminator-custom-form-9544 forminator-design--default  forminator_ajax\"\n\t\t\t\tmethod=\"post\"\n\t\t\t\tdata-forminator-render=\"0\"\n\t\t\t\tdata-form-id=\"9544\"\n\t\t\t\t data-color-option=\"default\" data-design=\"default\" data-grid=\"open\" style=\"display: none;\"\n\t\t\t\tdata-uid=\"6a576d082ce20\"\n\t\t\t><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><div class=\"forminator-row\"><div id=\"name-1\" class=\"forminator-field-name forminator-col forminator-col-6 \"><div class=\"forminator-row forminator-no-margin\" data-multiple=\"true\"><div class=\"forminator-col forminator-col-md-6\"><div class=\"forminator-field\"><label for=\"forminator-field-first-name-1_6a576d082ce20\" id=\"forminator-field-first-name-1_6a576d082ce20-label\" class=\"forminator-label\">Parent First Name: <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-1-first-name\" placeholder=\"E.g. John\" id=\"forminator-field-first-name-1_6a576d082ce20\" class=\"forminator-input\" aria-required=\"true\" data-multi=\"1\" autocomplete=\"given-name\" value=\"\" \/><\/div><\/div><div class=\"forminator-col forminator-col-md-6\"><div class=\"forminator-field\"><label for=\"forminator-field-last-name-1_6a576d082ce20\" id=\"forminator-field-last-name-1_6a576d082ce20-label\" class=\"forminator-label\">Parent Last Name: <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-1-last-name\" placeholder=\"E.g. Doe\" id=\"forminator-field-last-name-1_6a576d082ce20\" class=\"forminator-input\" aria-required=\"true\" data-multi=\"1\" autocomplete=\"family-name\" value=\"\" \/><\/div><\/div><\/div><\/div><div id=\"name-2\" class=\"forminator-field-name forminator-col forminator-col-6 \"><div class=\"forminator-row forminator-no-margin\" data-multiple=\"true\"><div class=\"forminator-col forminator-col-md-6\"><div class=\"forminator-field\"><label for=\"forminator-field-first-name-2_6a576d082ce20\" id=\"forminator-field-first-name-2_6a576d082ce20-label\" class=\"forminator-label\">Student First Name: <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-2-first-name\" placeholder=\"E.g. John\" id=\"forminator-field-first-name-2_6a576d082ce20\" class=\"forminator-input\" aria-required=\"true\" data-multi=\"1\" autocomplete=\"given-name\" value=\"\" \/><\/div><\/div><div class=\"forminator-col forminator-col-md-6\"><div class=\"forminator-field\"><label for=\"forminator-field-last-name-2_6a576d082ce20\" id=\"forminator-field-last-name-2_6a576d082ce20-label\" class=\"forminator-label\">Student Last Name: <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"name-2-last-name\" placeholder=\"E.g. Doe\" id=\"forminator-field-last-name-2_6a576d082ce20\" class=\"forminator-input\" aria-required=\"true\" data-multi=\"1\" autocomplete=\"family-name\" value=\"\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"date-2\" class=\"forminator-field-date forminator-col forminator-col-6 \"><label for=\"forminator-field-date-2\" id=\"forminator-field-date-2-label\" class=\"forminator-label\">Student Date of Birth (DD\/MM\/YY): <span class=\"forminator-required\">*<\/span><\/label><div class=\"forminator-date-select\"><div class=\"forminator-row\" data-multiple=\"true\"><div id=\"date-2-day\" class=\"forminator-col\"><div class=\"forminator-field\"><label for=\"forminator-field-9544__field--date-2-day_6a576d082ce20\" id=\"forminator-field-9544__field--date-2-day_6a576d082ce20-label\" class=\"forminator-label\">Day<\/label><select name=\"date-2-day\" id=\"forminator-field-9544__field--date-2-day_6a576d082ce20\" class=\"forminator-select2\" data-format=\"dd\/mm\/yy\" data-parent=\"date-2\" aria-labelledby=\"forminator-field-9544__field--date-2-day_6a576d082ce20-label\" data-default-value=\"15\"><option value=\"\" >Select day<\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" >7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><option value=\"13\" >13<\/option><option value=\"14\" >14<\/option><option value=\"15\" selected=\"selected\">15<\/option><option value=\"16\" >16<\/option><option value=\"17\" >17<\/option><option value=\"18\" >18<\/option><option value=\"19\" >19<\/option><option value=\"20\" >20<\/option><option value=\"21\" >21<\/option><option value=\"22\" >22<\/option><option value=\"23\" >23<\/option><option value=\"24\" >24<\/option><option value=\"25\" >25<\/option><option value=\"26\" >26<\/option><option value=\"27\" >27<\/option><option value=\"28\" >28<\/option><option value=\"29\" >29<\/option><option value=\"30\" >30<\/option><option value=\"31\" >31<\/option><\/select><\/div><\/div><div id=\"date-2-month\" class=\"forminator-col\"><div class=\"forminator-field\"><label for=\"forminator-field-9544__field--date-2-month_6a576d082ce20\" id=\"forminator-field-9544__field--date-2-month_6a576d082ce20-label\" class=\"forminator-label\">Month<\/label><select name=\"date-2-month\" id=\"forminator-field-9544__field--date-2-month_6a576d082ce20\" class=\"forminator-select2\" data-format=\"dd\/mm\/yy\" data-parent=\"date-2\" aria-labelledby=\"forminator-field-9544__field--date-2-month_6a576d082ce20-label\" data-default-value=\"7\"><option value=\"\" >Select month<\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" selected=\"selected\">7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><\/select><\/div><\/div><div id=\"date-2-year\" class=\"forminator-col\"><div class=\"forminator-field\"><label for=\"forminator-field-9544__field--date-2-year_6a576d082ce20\" id=\"forminator-field-9544__field--date-2-year_6a576d082ce20-label\" class=\"forminator-label\">Year<\/label><select name=\"date-2-year\" id=\"forminator-field-9544__field--date-2-year_6a576d082ce20\" class=\"forminator-select2\" data-format=\"dd\/mm\/yy\" data-parent=\"date-2\" aria-labelledby=\"forminator-field-9544__field--date-2-year_6a576d082ce20-label\" data-default-value=\"2026\"><option value=\"\" >Select Year<\/option><option value=\"2126\" >2126<\/option><option value=\"2125\" >2125<\/option><option value=\"2124\" >2124<\/option><option value=\"2123\" >2123<\/option><option value=\"2122\" >2122<\/option><option value=\"2121\" >2121<\/option><option value=\"2120\" >2120<\/option><option value=\"2119\" >2119<\/option><option value=\"2118\" >2118<\/option><option value=\"2117\" >2117<\/option><option value=\"2116\" >2116<\/option><option value=\"2115\" >2115<\/option><option value=\"2114\" >2114<\/option><option value=\"2113\" >2113<\/option><option value=\"2112\" >2112<\/option><option value=\"2111\" >2111<\/option><option value=\"2110\" >2110<\/option><option value=\"2109\" >2109<\/option><option value=\"2108\" >2108<\/option><option value=\"2107\" >2107<\/option><option value=\"2106\" >2106<\/option><option value=\"2105\" >2105<\/option><option value=\"2104\" >2104<\/option><option value=\"2103\" >2103<\/option><option value=\"2102\" >2102<\/option><option value=\"2101\" >2101<\/option><option value=\"2100\" >2100<\/option><option value=\"2099\" >2099<\/option><option value=\"2098\" >2098<\/option><option value=\"2097\" >2097<\/option><option value=\"2096\" >2096<\/option><option value=\"2095\" >2095<\/option><option value=\"2094\" >2094<\/option><option value=\"2093\" >2093<\/option><option value=\"2092\" >2092<\/option><option value=\"2091\" >2091<\/option><option value=\"2090\" >2090<\/option><option value=\"2089\" >2089<\/option><option value=\"2088\" >2088<\/option><option value=\"2087\" >2087<\/option><option value=\"2086\" >2086<\/option><option value=\"2085\" >2085<\/option><option value=\"2084\" >2084<\/option><option value=\"2083\" >2083<\/option><option value=\"2082\" >2082<\/option><option value=\"2081\" >2081<\/option><option value=\"2080\" >2080<\/option><option value=\"2079\" >2079<\/option><option value=\"2078\" >2078<\/option><option value=\"2077\" >2077<\/option><option value=\"2076\" >2076<\/option><option value=\"2075\" >2075<\/option><option value=\"2074\" >2074<\/option><option value=\"2073\" >2073<\/option><option value=\"2072\" >2072<\/option><option value=\"2071\" >2071<\/option><option value=\"2070\" >2070<\/option><option value=\"2069\" >2069<\/option><option value=\"2068\" >2068<\/option><option value=\"2067\" >2067<\/option><option value=\"2066\" >2066<\/option><option value=\"2065\" >2065<\/option><option value=\"2064\" >2064<\/option><option value=\"2063\" >2063<\/option><option value=\"2062\" >2062<\/option><option value=\"2061\" >2061<\/option><option value=\"2060\" >2060<\/option><option value=\"2059\" >2059<\/option><option value=\"2058\" >2058<\/option><option value=\"2057\" >2057<\/option><option value=\"2056\" >2056<\/option><option value=\"2055\" >2055<\/option><option value=\"2054\" >2054<\/option><option value=\"2053\" >2053<\/option><option value=\"2052\" >2052<\/option><option value=\"2051\" >2051<\/option><option value=\"2050\" >2050<\/option><option value=\"2049\" >2049<\/option><option value=\"2048\" >2048<\/option><option value=\"2047\" >2047<\/option><option value=\"2046\" >2046<\/option><option value=\"2045\" >2045<\/option><option value=\"2044\" >2044<\/option><option value=\"2043\" >2043<\/option><option value=\"2042\" >2042<\/option><option value=\"2041\" >2041<\/option><option value=\"2040\" >2040<\/option><option value=\"2039\" >2039<\/option><option value=\"2038\" >2038<\/option><option value=\"2037\" >2037<\/option><option value=\"2036\" >2036<\/option><option value=\"2035\" >2035<\/option><option value=\"2034\" >2034<\/option><option value=\"2033\" >2033<\/option><option value=\"2032\" >2032<\/option><option value=\"2031\" >2031<\/option><option value=\"2030\" >2030<\/option><option value=\"2029\" >2029<\/option><option value=\"2028\" >2028<\/option><option value=\"2027\" >2027<\/option><option value=\"2026\" selected=\"selected\">2026<\/option><option value=\"2025\" >2025<\/option><option value=\"2024\" >2024<\/option><option value=\"2023\" >2023<\/option><option value=\"2022\" >2022<\/option><option value=\"2021\" >2021<\/option><option value=\"2020\" >2020<\/option><option value=\"2019\" >2019<\/option><option value=\"2018\" >2018<\/option><option value=\"2017\" >2017<\/option><option value=\"2016\" >2016<\/option><option value=\"2015\" >2015<\/option><option value=\"2014\" >2014<\/option><option value=\"2013\" >2013<\/option><option value=\"2012\" >2012<\/option><option value=\"2011\" >2011<\/option><option value=\"2010\" >2010<\/option><option value=\"2009\" >2009<\/option><option value=\"2008\" >2008<\/option><option value=\"2007\" >2007<\/option><option value=\"2006\" >2006<\/option><option value=\"2005\" >2005<\/option><option value=\"2004\" >2004<\/option><option value=\"2003\" >2003<\/option><option value=\"2002\" >2002<\/option><option value=\"2001\" >2001<\/option><option value=\"2000\" >2000<\/option><option value=\"1999\" >1999<\/option><option value=\"1998\" >1998<\/option><option value=\"1997\" >1997<\/option><option value=\"1996\" >1996<\/option><option value=\"1995\" >1995<\/option><option value=\"1994\" >1994<\/option><option value=\"1993\" >1993<\/option><option value=\"1992\" >1992<\/option><option value=\"1991\" >1991<\/option><option value=\"1990\" >1990<\/option><option value=\"1989\" >1989<\/option><option value=\"1988\" >1988<\/option><option value=\"1987\" >1987<\/option><option value=\"1986\" >1986<\/option><option value=\"1985\" >1985<\/option><option value=\"1984\" >1984<\/option><option value=\"1983\" >1983<\/option><option value=\"1982\" >1982<\/option><option value=\"1981\" >1981<\/option><option value=\"1980\" >1980<\/option><option value=\"1979\" >1979<\/option><option value=\"1978\" >1978<\/option><option value=\"1977\" >1977<\/option><option value=\"1976\" >1976<\/option><option value=\"1975\" >1975<\/option><option value=\"1974\" >1974<\/option><option value=\"1973\" >1973<\/option><option value=\"1972\" >1972<\/option><option value=\"1971\" >1971<\/option><option value=\"1970\" >1970<\/option><option value=\"1969\" >1969<\/option><option value=\"1968\" >1968<\/option><option value=\"1967\" >1967<\/option><option value=\"1966\" >1966<\/option><option value=\"1965\" >1965<\/option><option value=\"1964\" >1964<\/option><option value=\"1963\" >1963<\/option><option value=\"1962\" >1962<\/option><option value=\"1961\" >1961<\/option><option value=\"1960\" >1960<\/option><option value=\"1959\" >1959<\/option><option value=\"1958\" >1958<\/option><option value=\"1957\" >1957<\/option><option value=\"1956\" >1956<\/option><option value=\"1955\" >1955<\/option><option value=\"1954\" >1954<\/option><option value=\"1953\" >1953<\/option><option value=\"1952\" >1952<\/option><option value=\"1951\" >1951<\/option><option value=\"1950\" >1950<\/option><option value=\"1949\" >1949<\/option><option value=\"1948\" >1948<\/option><option value=\"1947\" >1947<\/option><option value=\"1946\" >1946<\/option><option value=\"1945\" >1945<\/option><option value=\"1944\" >1944<\/option><option value=\"1943\" >1943<\/option><option value=\"1942\" >1942<\/option><option value=\"1941\" >1941<\/option><option value=\"1940\" >1940<\/option><option value=\"1939\" >1939<\/option><option value=\"1938\" >1938<\/option><option value=\"1937\" >1937<\/option><option value=\"1936\" >1936<\/option><option value=\"1935\" >1935<\/option><option value=\"1934\" >1934<\/option><option value=\"1933\" >1933<\/option><option value=\"1932\" >1932<\/option><option value=\"1931\" >1931<\/option><option value=\"1930\" >1930<\/option><option value=\"1929\" >1929<\/option><option value=\"1928\" >1928<\/option><option value=\"1927\" >1927<\/option><option value=\"1926\" >1926<\/option><\/select><\/div><\/div><\/div><\/div><\/div><div id=\"radio-1\" class=\"forminator-field-radio forminator-col forminator-col-6 \"><div role=\"radiogroup\" class=\"forminator-field\" aria-labelledby=\"forminator-radiogroup-radio-1-6a576d082ce20-label\"><span id=\"forminator-radiogroup-radio-1-6a576d082ce20-label\" class=\"forminator-label\">Gender :<\/span><label id=\"forminator-field-radio-1-label-1\" for=\"forminator-field-radio-1-1-6a576d082ce20\" class=\"forminator-radio\" title=\"Male\"><input type=\"radio\" name=\"radio-1\" value=\"Male\" id=\"forminator-field-radio-1-1-6a576d082ce20\" aria-labelledby=\"forminator-field-radio-1-label-1\" data-calculation=\"0\"  \/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">Male<\/span><\/label><label id=\"forminator-field-radio-1-label-2\" for=\"forminator-field-radio-1-2-6a576d082ce20\" class=\"forminator-radio\" title=\"Female\"><input type=\"radio\" name=\"radio-1\" value=\"Female\" id=\"forminator-field-radio-1-2-6a576d082ce20\" aria-labelledby=\"forminator-field-radio-1-label-2\" data-calculation=\"0\"  \/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">Female<\/span><\/label><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"radio-2\" class=\"forminator-field-radio forminator-col forminator-col-12 \"><div role=\"radiogroup\" class=\"forminator-field\" aria-labelledby=\"forminator-radiogroup-radio-2-6a576d082ce20-label\"><span id=\"forminator-radiogroup-radio-2-6a576d082ce20-label\" class=\"forminator-label\">Select your interest <span class=\"forminator-required\">*<\/span><\/span><label id=\"forminator-field-radio-2-label-1\" for=\"forminator-field-radio-2-1-6a576d082ce20\" class=\"forminator-radio forminator-radio-inline\" title=\"Angel&#039;s kindergarten\"><input type=\"radio\" name=\"radio-2\" value=\"one\" id=\"forminator-field-radio-2-1-6a576d082ce20\" aria-labelledby=\"forminator-field-radio-2-label-1\" data-calculation=\"0\"  \/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">Angel's kindergarten<\/span><\/label><label id=\"forminator-field-radio-2-label-2\" for=\"forminator-field-radio-2-2-6a576d082ce20\" class=\"forminator-radio forminator-radio-inline\" title=\"Primary school\"><input type=\"radio\" name=\"radio-2\" value=\"two\" id=\"forminator-field-radio-2-2-6a576d082ce20\" aria-labelledby=\"forminator-field-radio-2-label-2\" data-calculation=\"0\"  \/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">Primary school<\/span><\/label><label id=\"forminator-field-radio-2-label-3\" for=\"forminator-field-radio-2-3-6a576d082ce20\" class=\"forminator-radio forminator-radio-inline\" title=\"Secondary school\"><input type=\"radio\" name=\"radio-2\" value=\"Secondary-school\" id=\"forminator-field-radio-2-3-6a576d082ce20\" aria-labelledby=\"forminator-field-radio-2-label-3\" data-calculation=\"0\"  \/><span class=\"forminator-radio-bullet\" aria-hidden=\"true\"><\/span><span class=\"forminator-radio-label\">Secondary school<\/span><\/label><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"text-1\" class=\"forminator-field-text forminator-col forminator-col-6 \"><div class=\"forminator-field\"><label for=\"forminator-field-text-1_6a576d082ce20\" id=\"forminator-field-text-1_6a576d082ce20-label\" class=\"forminator-label\">Nationality: <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"text-1\" value=\"\" placeholder=\"\" id=\"forminator-field-text-1_6a576d082ce20\" class=\"forminator-input forminator-name--field\" data-required=\"1\" maxlength=\"20\" \/><span id=\"forminator-field-text-1_6a576d082ce20-description\" class=\"forminator-description\"><span data-limit=\"20\" data-type=\"characters\">0 \/ 20<\/span><\/span><\/div><\/div><div id=\"select-1\" class=\"forminator-field-select forminator-col forminator-col-6 \"><div class=\"forminator-field\"><label for=\"forminator-form-9544__field--select-1_6a576d082ce20\" id=\"forminator-form-9544__field--select-1_6a576d082ce20-label\" class=\"forminator-label\">School &amp; Class of Interest: <span class=\"forminator-required\">*<\/span><\/label><select  id=\"forminator-form-9544__field--select-1_6a576d082ce20\" class=\"forminator-select--field forminator-select2 forminator-select2-multiple\" data-required=\"1\" name=\"select-1\" data-default-value=\"Primary-5-12-yo\" data-placeholder=\"Please select an option\" data-search=\"false\" data-search-placeholder=\"Please select an option\" data-checkbox=\"false\" data-allow-clear=\"false\" aria-labelledby=\"forminator-form-9544__field--select-1_6a576d082ce20-label\"><option value=\"\"  >Please select an option<\/option><option value=\"Kindergarden-2-5-yo\"  data-calculation=\"0\">Kindergarden 2-5 yo<\/option><option value=\"Primary-5-12-yo\" selected=\"selected\" data-calculation=\"0\">Primary 5-12 yo<\/option><option value=\"Secoundary-12-18-yo\"  data-calculation=\"0\">Secoundary 12-18 yo<\/option><option value=\"Greek-School-12-18-yo\"  data-calculation=\"0\">Greek School 12-18 yo<\/option><option value=\"Boarding-School-12-18-yo\"  data-calculation=\"0\">Boarding School 12-18 yo<\/option><\/select><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"html-1\" class=\"forminator-field-html forminator-col forminator-col-12 \"><div class=\"forminator-field forminator-merge-tags\" data-field=\"html-1\"><h4>Dates of Preferred Visit:<\/h4><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"date-1\" class=\"forminator-field-date forminator-col forminator-col-12 \"><label for=\"forminator-field-date-1\" id=\"forminator-field-date-1-label\" class=\"forminator-label\">Date <span class=\"forminator-required\">*<\/span><\/label><div class=\"forminator-date-select\"><div class=\"forminator-row\" data-multiple=\"true\"><div id=\"date-1-day\" class=\"forminator-col\"><div class=\"forminator-field\"><label for=\"forminator-field-9544__field--date-1-day_6a576d082ce20\" id=\"forminator-field-9544__field--date-1-day_6a576d082ce20-label\" class=\"forminator-label\">Day<\/label><select name=\"date-1-day\" id=\"forminator-field-9544__field--date-1-day_6a576d082ce20\" class=\"forminator-select2\" data-format=\"dd-mm-yy\" data-parent=\"date-1\" aria-labelledby=\"forminator-field-9544__field--date-1-day_6a576d082ce20-label\" data-default-value=\"\"><option value=\"\" selected=\"selected\">Select day<\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" >7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><option value=\"13\" >13<\/option><option value=\"14\" >14<\/option><option value=\"15\" >15<\/option><option value=\"16\" >16<\/option><option value=\"17\" >17<\/option><option value=\"18\" >18<\/option><option value=\"19\" >19<\/option><option value=\"20\" >20<\/option><option value=\"21\" >21<\/option><option value=\"22\" >22<\/option><option value=\"23\" >23<\/option><option value=\"24\" >24<\/option><option value=\"25\" >25<\/option><option value=\"26\" >26<\/option><option value=\"27\" >27<\/option><option value=\"28\" >28<\/option><option value=\"29\" >29<\/option><option value=\"30\" >30<\/option><option value=\"31\" >31<\/option><\/select><\/div><\/div><div id=\"date-1-month\" class=\"forminator-col\"><div class=\"forminator-field\"><label for=\"forminator-field-9544__field--date-1-month_6a576d082ce20\" id=\"forminator-field-9544__field--date-1-month_6a576d082ce20-label\" class=\"forminator-label\">Month<\/label><select name=\"date-1-month\" id=\"forminator-field-9544__field--date-1-month_6a576d082ce20\" class=\"forminator-select2\" data-format=\"dd-mm-yy\" data-parent=\"date-1\" aria-labelledby=\"forminator-field-9544__field--date-1-month_6a576d082ce20-label\" data-default-value=\"\"><option value=\"\" selected=\"selected\">Select month<\/option><option value=\"1\" >1<\/option><option value=\"2\" >2<\/option><option value=\"3\" >3<\/option><option value=\"4\" >4<\/option><option value=\"5\" >5<\/option><option value=\"6\" >6<\/option><option value=\"7\" >7<\/option><option value=\"8\" >8<\/option><option value=\"9\" >9<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><\/select><\/div><\/div><div id=\"date-1-year\" class=\"forminator-col\"><div class=\"forminator-field\"><label for=\"forminator-field-9544__field--date-1-year_6a576d082ce20\" id=\"forminator-field-9544__field--date-1-year_6a576d082ce20-label\" class=\"forminator-label\">Year<\/label><select name=\"date-1-year\" id=\"forminator-field-9544__field--date-1-year_6a576d082ce20\" class=\"forminator-select2\" data-format=\"dd-mm-yy\" data-parent=\"date-1\" aria-labelledby=\"forminator-field-9544__field--date-1-year_6a576d082ce20-label\" data-default-value=\"2026\"><option value=\"\" >Select Year<\/option><option value=\"2126\" >2126<\/option><option value=\"2125\" >2125<\/option><option value=\"2124\" >2124<\/option><option value=\"2123\" >2123<\/option><option value=\"2122\" >2122<\/option><option value=\"2121\" >2121<\/option><option value=\"2120\" >2120<\/option><option value=\"2119\" >2119<\/option><option value=\"2118\" >2118<\/option><option value=\"2117\" >2117<\/option><option value=\"2116\" >2116<\/option><option value=\"2115\" >2115<\/option><option value=\"2114\" >2114<\/option><option value=\"2113\" >2113<\/option><option value=\"2112\" >2112<\/option><option value=\"2111\" >2111<\/option><option value=\"2110\" >2110<\/option><option value=\"2109\" >2109<\/option><option value=\"2108\" >2108<\/option><option value=\"2107\" >2107<\/option><option value=\"2106\" >2106<\/option><option value=\"2105\" >2105<\/option><option value=\"2104\" >2104<\/option><option value=\"2103\" >2103<\/option><option value=\"2102\" >2102<\/option><option value=\"2101\" >2101<\/option><option value=\"2100\" >2100<\/option><option value=\"2099\" >2099<\/option><option value=\"2098\" >2098<\/option><option value=\"2097\" >2097<\/option><option value=\"2096\" >2096<\/option><option value=\"2095\" >2095<\/option><option value=\"2094\" >2094<\/option><option value=\"2093\" >2093<\/option><option value=\"2092\" >2092<\/option><option value=\"2091\" >2091<\/option><option value=\"2090\" >2090<\/option><option value=\"2089\" >2089<\/option><option value=\"2088\" >2088<\/option><option value=\"2087\" >2087<\/option><option value=\"2086\" >2086<\/option><option value=\"2085\" >2085<\/option><option value=\"2084\" >2084<\/option><option value=\"2083\" >2083<\/option><option value=\"2082\" >2082<\/option><option value=\"2081\" >2081<\/option><option value=\"2080\" >2080<\/option><option value=\"2079\" >2079<\/option><option value=\"2078\" >2078<\/option><option value=\"2077\" >2077<\/option><option value=\"2076\" >2076<\/option><option value=\"2075\" >2075<\/option><option value=\"2074\" >2074<\/option><option value=\"2073\" >2073<\/option><option value=\"2072\" >2072<\/option><option value=\"2071\" >2071<\/option><option value=\"2070\" >2070<\/option><option value=\"2069\" >2069<\/option><option value=\"2068\" >2068<\/option><option value=\"2067\" >2067<\/option><option value=\"2066\" >2066<\/option><option value=\"2065\" >2065<\/option><option value=\"2064\" >2064<\/option><option value=\"2063\" >2063<\/option><option value=\"2062\" >2062<\/option><option value=\"2061\" >2061<\/option><option value=\"2060\" >2060<\/option><option value=\"2059\" >2059<\/option><option value=\"2058\" >2058<\/option><option value=\"2057\" >2057<\/option><option value=\"2056\" >2056<\/option><option value=\"2055\" >2055<\/option><option value=\"2054\" >2054<\/option><option value=\"2053\" >2053<\/option><option value=\"2052\" >2052<\/option><option value=\"2051\" >2051<\/option><option value=\"2050\" >2050<\/option><option value=\"2049\" >2049<\/option><option value=\"2048\" >2048<\/option><option value=\"2047\" >2047<\/option><option value=\"2046\" >2046<\/option><option value=\"2045\" >2045<\/option><option value=\"2044\" >2044<\/option><option value=\"2043\" >2043<\/option><option value=\"2042\" >2042<\/option><option value=\"2041\" >2041<\/option><option value=\"2040\" >2040<\/option><option value=\"2039\" >2039<\/option><option value=\"2038\" >2038<\/option><option value=\"2037\" >2037<\/option><option value=\"2036\" >2036<\/option><option value=\"2035\" >2035<\/option><option value=\"2034\" >2034<\/option><option value=\"2033\" >2033<\/option><option value=\"2032\" >2032<\/option><option value=\"2031\" >2031<\/option><option value=\"2030\" >2030<\/option><option value=\"2029\" >2029<\/option><option value=\"2028\" >2028<\/option><option value=\"2027\" >2027<\/option><option value=\"2026\" selected=\"selected\">2026<\/option><option value=\"2025\" >2025<\/option><option value=\"2024\" >2024<\/option><option value=\"2023\" >2023<\/option><option value=\"2022\" >2022<\/option><option value=\"2021\" >2021<\/option><option value=\"2020\" >2020<\/option><option value=\"2019\" >2019<\/option><option value=\"2018\" >2018<\/option><option value=\"2017\" >2017<\/option><option value=\"2016\" >2016<\/option><option value=\"2015\" >2015<\/option><option value=\"2014\" >2014<\/option><option value=\"2013\" >2013<\/option><option value=\"2012\" >2012<\/option><option value=\"2011\" >2011<\/option><option value=\"2010\" >2010<\/option><option value=\"2009\" >2009<\/option><option value=\"2008\" >2008<\/option><option value=\"2007\" >2007<\/option><option value=\"2006\" >2006<\/option><option value=\"2005\" >2005<\/option><option value=\"2004\" >2004<\/option><option value=\"2003\" >2003<\/option><option value=\"2002\" >2002<\/option><option value=\"2001\" >2001<\/option><option value=\"2000\" >2000<\/option><option value=\"1999\" >1999<\/option><option value=\"1998\" >1998<\/option><option value=\"1997\" >1997<\/option><option value=\"1996\" >1996<\/option><option value=\"1995\" >1995<\/option><option value=\"1994\" >1994<\/option><option value=\"1993\" >1993<\/option><option value=\"1992\" >1992<\/option><option value=\"1991\" >1991<\/option><option value=\"1990\" >1990<\/option><option value=\"1989\" >1989<\/option><option value=\"1988\" >1988<\/option><option value=\"1987\" >1987<\/option><option value=\"1986\" >1986<\/option><option value=\"1985\" >1985<\/option><option value=\"1984\" >1984<\/option><option value=\"1983\" >1983<\/option><option value=\"1982\" >1982<\/option><option value=\"1981\" >1981<\/option><option value=\"1980\" >1980<\/option><option value=\"1979\" >1979<\/option><option value=\"1978\" >1978<\/option><option value=\"1977\" >1977<\/option><option value=\"1976\" >1976<\/option><option value=\"1975\" >1975<\/option><option value=\"1974\" >1974<\/option><option value=\"1973\" >1973<\/option><option value=\"1972\" >1972<\/option><option value=\"1971\" >1971<\/option><option value=\"1970\" >1970<\/option><option value=\"1969\" >1969<\/option><option value=\"1968\" >1968<\/option><option value=\"1967\" >1967<\/option><option value=\"1966\" >1966<\/option><option value=\"1965\" >1965<\/option><option value=\"1964\" >1964<\/option><option value=\"1963\" >1963<\/option><option value=\"1962\" >1962<\/option><option value=\"1961\" >1961<\/option><option value=\"1960\" >1960<\/option><option value=\"1959\" >1959<\/option><option value=\"1958\" >1958<\/option><option value=\"1957\" >1957<\/option><option value=\"1956\" >1956<\/option><option value=\"1955\" >1955<\/option><option value=\"1954\" >1954<\/option><option value=\"1953\" >1953<\/option><option value=\"1952\" >1952<\/option><option value=\"1951\" >1951<\/option><option value=\"1950\" >1950<\/option><option value=\"1949\" >1949<\/option><option value=\"1948\" >1948<\/option><option value=\"1947\" >1947<\/option><option value=\"1946\" >1946<\/option><option value=\"1945\" >1945<\/option><option value=\"1944\" >1944<\/option><option value=\"1943\" >1943<\/option><option value=\"1942\" >1942<\/option><option value=\"1941\" >1941<\/option><option value=\"1940\" >1940<\/option><option value=\"1939\" >1939<\/option><option value=\"1938\" >1938<\/option><option value=\"1937\" >1937<\/option><option value=\"1936\" >1936<\/option><option value=\"1935\" >1935<\/option><option value=\"1934\" >1934<\/option><option value=\"1933\" >1933<\/option><option value=\"1932\" >1932<\/option><option value=\"1931\" >1931<\/option><option value=\"1930\" >1930<\/option><option value=\"1929\" >1929<\/option><option value=\"1928\" >1928<\/option><option value=\"1927\" >1927<\/option><option value=\"1926\" >1926<\/option><\/select><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"html-2\" class=\"forminator-field-html forminator-col forminator-col-12 \"><div class=\"forminator-field forminator-merge-tags\" data-field=\"html-2\"><p><strong>Please note that the visiting hours are between 9:00am 14:00pm on week days.<\/strong><\/p><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"time-1\" class=\"forminator-field-time forminator-col forminator-col-12 \"><div class=\"forminator-timepicker\" ><div class=\"forminator-row\" data-multiple=\"true\"><div id=\"time-1-hours\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><label for=\"forminator-field-9544__field--time-1-hours_6a576d082ce20\" id=\"forminator-field-9544__field--time-1-hours_6a576d082ce20-label\" class=\"forminator-label\">Hours <span class=\"forminator-required\">*<\/span><\/label><select name=\"time-1-hours\" id=\"forminator-field-9544__field--time-1-hours_6a576d082ce20\" class=\"forminator-select2 time-hours has-time-limiter\" data-field=\"hours\" data-placeholder=\"Select\" aria-labelledby=\"forminator-field-9544__field--time-1-hours_6a576d082ce20-label\" data-default-value=\"\"><option value=\"\" selected=\"selected\">-<\/option><option value=\"9\" >09<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><option value=\"13\" >13<\/option><option value=\"14\" >14<\/option><\/select><\/div><\/div><div id=\"time-1-minutes\" class=\"forminator-col forminator-col-6\"><div class=\"forminator-field\"><label for=\"forminator-field-9544__field--time-1-minutes_6a576d082ce20\" id=\"forminator-field-9544__field--time-1-minutes_6a576d082ce20-label\" class=\"forminator-label\">Minutes <span class=\"forminator-required\">*<\/span><\/label><select name=\"time-1-minutes\" id=\"forminator-field-9544__field--time-1-minutes_6a576d082ce20\" class=\"forminator-select2 time-minutes has-time-limiter\" data-field=\"minutes\" data-placeholder=\"Select\" aria-labelledby=\"forminator-field-9544__field--time-1-minutes_6a576d082ce20-label\" data-default-value=\"\"><option value=\"\" selected=\"selected\">-<\/option><option value=\"0\" >00<\/option><option value=\"1\" >01<\/option><option value=\"2\" >02<\/option><option value=\"3\" >03<\/option><option value=\"4\" >04<\/option><option value=\"5\" >05<\/option><option value=\"6\" >06<\/option><option value=\"7\" >07<\/option><option value=\"8\" >08<\/option><option value=\"9\" >09<\/option><option value=\"10\" >10<\/option><option value=\"11\" >11<\/option><option value=\"12\" >12<\/option><option value=\"13\" >13<\/option><option value=\"14\" >14<\/option><option value=\"15\" >15<\/option><option value=\"16\" >16<\/option><option value=\"17\" >17<\/option><option value=\"18\" >18<\/option><option value=\"19\" >19<\/option><option value=\"20\" >20<\/option><option value=\"21\" >21<\/option><option value=\"22\" >22<\/option><option value=\"23\" >23<\/option><option value=\"24\" >24<\/option><option value=\"25\" >25<\/option><option value=\"26\" >26<\/option><option value=\"27\" >27<\/option><option value=\"28\" >28<\/option><option value=\"29\" >29<\/option><option value=\"30\" >30<\/option><option value=\"31\" >31<\/option><option value=\"32\" >32<\/option><option value=\"33\" >33<\/option><option value=\"34\" >34<\/option><option value=\"35\" >35<\/option><option value=\"36\" >36<\/option><option value=\"37\" >37<\/option><option value=\"38\" >38<\/option><option value=\"39\" >39<\/option><option value=\"40\" >40<\/option><option value=\"41\" >41<\/option><option value=\"42\" >42<\/option><option value=\"43\" >43<\/option><option value=\"44\" >44<\/option><option value=\"45\" >45<\/option><option value=\"46\" >46<\/option><option value=\"47\" >47<\/option><option value=\"48\" >48<\/option><option value=\"49\" >49<\/option><option value=\"50\" >50<\/option><option value=\"51\" >51<\/option><option value=\"52\" >52<\/option><option value=\"53\" >53<\/option><option value=\"54\" >54<\/option><option value=\"55\" >55<\/option><option value=\"56\" >56<\/option><option value=\"57\" >57<\/option><option value=\"58\" >58<\/option><option value=\"59\" >59<\/option><\/select><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"phone-1\" class=\"forminator-field-phone forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-phone-1_6a576d082ce20\" id=\"forminator-field-phone-1_6a576d082ce20-label\" class=\"forminator-label\">Contact Number <span class=\"forminator-required\">*<\/span><\/label><input type=\"text\" name=\"phone-1\" value=\"\" placeholder=\"E.g. +1 300 400 5000\" id=\"forminator-field-phone-1_6a576d082ce20\" class=\"forminator-input forminator-field--phone\" data-required=\"1\" aria-required=\"true\" autocomplete=\"off\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"email-1\" class=\"forminator-field-email forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-email-1_6a576d082ce20\" id=\"forminator-field-email-1_6a576d082ce20-label\" class=\"forminator-label\">Email Address <span class=\"forminator-required\">*<\/span><\/label><input type=\"email\" name=\"email-1\" value=\"\" placeholder=\"E.g. john@doe.com\" id=\"forminator-field-email-1_6a576d082ce20\" class=\"forminator-input forminator-email--field\" data-required=\"1\" aria-required=\"true\" autocomplete=\"email\" \/><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"consent-1\" class=\"forminator-field-consent forminator-col forminator-col-12 \"><div class=\"forminator-field\"><label for=\"forminator-field-consent-1_6a576d082ce20\" id=\"forminator-field-consent-1_6a576d082ce20-label\" class=\"forminator-label\">Consent <span class=\"forminator-required\">*<\/span><\/label><div class=\"forminator-checkbox__wrapper\"><label id=\"forminator-field-consent-1_6a576d082ce20__label\" class=\"forminator-checkbox forminator-consent\"><input type=\"checkbox\" name=\"consent-1\" id=\"forminator-field-consent-1_6a576d082ce20\" value=\"checked\" aria-labelledby=\"forminator-field-consent-1_6a576d082ce20-label\" aria-describedby=\"forminator-field-consent-1_6a576d082ce20__description\" data-required=\"true\" aria-required=\"true\" \/><span class=\"forminator-checkbox-box\" aria-hidden=\"true\"><\/span><\/label><div id=\"forminator-field-consent-1_6a576d082ce20__description\" class=\"forminator-checkbox__label forminator-consent__label\"><p>Please note that the above Requested Date &amp; Time is not a confirmed appointment. We will get back to you if the date &amp; time is suitable or we will contact you with another suitable appointment.<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"forminator-row\"><div id=\"captcha-1\" class=\"forminator-field-captcha forminator-col forminator-col-12 \"><div class=\"forminator-captcha-left forminator-g-recaptcha\" data-theme=\"light\"  data-sitekey=\"6LehimghAAAAACeFxHmseX5Bp0jyghJqPJHyQRlG\" data-size=\"normal\"><\/div> <\/div><\/div><input type=\"hidden\" name=\"referer_url\" value=\"\" \/><div class=\"forminator-row forminator-row-last\"><div class=\"forminator-col\"><div class=\"forminator-field\"><button class=\"forminator-button forminator-button-submit\">Send Message<\/button><\/div><\/div><\/div><input type=\"hidden\" id=\"forminator_nonce\" name=\"forminator_nonce\" value=\"29f0007140\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/el\/wp-json\/wp\/v2\/posts\/32977\" \/><input type=\"hidden\" name=\"form_id\" value=\"9544\"><input type=\"hidden\" name=\"page_id\" value=\"0\"><input type=\"hidden\" name=\"form_type\" value=\"default\"><input type=\"hidden\" name=\"current_url\" value=\"\"><input type=\"hidden\" name=\"render_id\" value=\"0\"><input type=\"hidden\" name=\"action\" value=\"forminator_submit_form_custom-forms\"><\/form>\n<\/div>\n\t\t<\/div>\n\t\t<div id=\"panel-32977-0-0-2\" class=\"so-panel widget widget_recent-posts widget_recent_entries panel-last-child\" data-index=\"2\" >\n\t\t<h3 class=\"widget-title\">Recent Posts<\/h3>\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/americanacademy.ac.cy\/el\/our-primary-summer-school-2\/\">Our Primary Summer School<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/americanacademy.ac.cy\/el\/farewell-to-a-fantastic-summer\/\">Farewell to a Fantastic Summer!<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/americanacademy.ac.cy\/el\/our-primary-school-students-had-an-exciting-week\/\">Our primary school students had an exciting week<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/americanacademy.ac.cy\/el\/angels-kindergarten-summer-school\/\">Angel&#8217;s Kindergarten summer school<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/americanacademy.ac.cy\/el\/week-3-of-summer-school\/\">Week 3 of Summer School<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Contact us<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[12],"tags":[29,4604,5810],"class_list":["post-32977","post","type-post","status-publish","format-standard","hentry","category-12","tag-american-academy-el","tag-american-academy-private-primary-school","tag-donate-blood-el"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Contact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\/MM\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel&#039;s kindergartenPrimary schoolSecondary schoolNationality: *0 \/ 20School &amp; Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of PreferredContact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\/MM\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel&#039;s kindergartenPrimary schoolSecondary schoolNationality: *0 \/ 20School &amp; Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of Preferred Donate blood \u2013 safe a life\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"American Academy\"\/>\n\t<meta name=\"google-site-verification\" content=\"1GBqZ9YhyEObwKVlJAz6t3iyq0TUQlYqLJq8PYiTPKE\" \/>\n\t<meta name=\"msvalidate.01\" content=\"0D6AFA9A4E16BE096B4C1467E7612150\" \/>\n\t<meta name=\"yandex-verification\" content=\"f1e4b306a7b5a60d\" \/>\n\t<meta name=\"keywords\" content=\"donate blood,american academy,american academy (private) primary school,\u03bd\u03ad\u03b1 &amp; \u03b5\u03ba\u03b4\u03b7\u03bb\u03ce\u03c3\u03b5\u03b9\u03c2\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AMERICAN PRIVATE SCHOOLS\u00a0LTD \u2022 AMERICAN PRIVATE SCHOOLS\u00a0LTD\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Donate blood \u2013 safe a life | AMERICAN PRIVATE SCHOOLS LTD\" \/>\n\t\t<meta property=\"og:description\" content=\"Contact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\/MM\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel&#039;s kindergartenPrimary schoolSecondary schoolNationality: *0 \/ 20School &amp; Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of PreferredContact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\/MM\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel&#039;s kindergartenPrimary schoolSecondary schoolNationality: *0 \/ 20School &amp; Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of Preferred Donate blood \u2013 safe a life\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/09\/Logo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/09\/Logo.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"752\" \/>\n\t\t<meta property=\"og:image:height\" content=\"813\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-28T18:59:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-01-28T19:02:07+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/American-Academy-Athletic-School-107035131005337\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/#article\",\"name\":\"Donate blood \\u2013 safe a life | AMERICAN PRIVATE SCHOOLS LTD\",\"headline\":\"Donate blood &#8211; safe a life\",\"author\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/author\\\/amac\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.jpg\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/#articleImage\",\"width\":752,\"height\":813,\"caption\":\"American Academy Logo\"},\"datePublished\":\"2025-01-28T20:59:30+02:00\",\"dateModified\":\"2025-01-28T21:02:07+02:00\",\"inLanguage\":\"el-EL\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/#webpage\"},\"articleSection\":\"\\u039d\\u03ad\\u03b1 &amp; \\u0395\\u03ba\\u03b4\\u03b7\\u03bb\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2, American Academy, American Academy (Private) Primary School, donate blood, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/category\\\/%ce%bd%ce%ad%ce%b1\\\/#listItem\",\"name\":\"\\u039d\\u03ad\\u03b1 &amp; \\u0395\\u03ba\\u03b4\\u03b7\\u03bb\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/category\\\/%ce%bd%ce%ad%ce%b1\\\/#listItem\",\"position\":2,\"name\":\"\\u039d\\u03ad\\u03b1 &amp; \\u0395\\u03ba\\u03b4\\u03b7\\u03bb\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\",\"item\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/category\\\/%ce%bd%ce%ad%ce%b1\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/#listItem\",\"name\":\"Donate blood &#8211; safe a life\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/#listItem\",\"position\":3,\"name\":\"Donate blood &#8211; safe a life\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/category\\\/%ce%bd%ce%ad%ce%b1\\\/#listItem\",\"name\":\"\\u039d\\u03ad\\u03b1 &amp; \\u0395\\u03ba\\u03b4\\u03b7\\u03bb\\u03ce\\u03c3\\u03b5\\u03b9\\u03c2\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/#organization\",\"name\":\"American Academy Limassol\",\"description\":\"AMERICAN PRIVATE SCHOOLS\\u00a0LTD\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/\",\"telephone\":\"+35725337054\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Logo.jpg\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/#organizationLogo\",\"width\":752,\"height\":813,\"caption\":\"American Academy Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/American-Academy-Athletic-School-107035131005337\",\"https:\\\/\\\/www.instagram.com\\\/americanacademyprivate\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCgEJukzLPVITvwtccVN0N3w\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/american-academy-school\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/author\\\/amac\\\/#author\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/author\\\/amac\\\/\",\"name\":\"American Academy\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/#webpage\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/\",\"name\":\"Donate blood \\u2013 safe a life | AMERICAN PRIVATE SCHOOLS LTD\",\"description\":\"Contact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\\\/MM\\\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel's kindergartenPrimary schoolSecondary schoolNationality: *0 \\\/ 20School & Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of PreferredContact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\\\/MM\\\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel's kindergartenPrimary schoolSecondary schoolNationality: *0 \\\/ 20School & Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of Preferred Donate blood \\u2013 safe a life\",\"inLanguage\":\"el-EL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/donate-blood-safe-a-life\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/author\\\/amac\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/author\\\/amac\\\/#author\"},\"datePublished\":\"2025-01-28T20:59:30+02:00\",\"dateModified\":\"2025-01-28T21:02:07+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/#website\",\"url\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/\",\"name\":\"American Academy Limassol\",\"description\":\"AMERICAN PRIVATE SCHOOLS\\u00a0LTD\",\"inLanguage\":\"el-EL\",\"publisher\":{\"@id\":\"https:\\\/\\\/americanacademy.ac.cy\\\/el\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Donate blood \u2013 safe a life | AMERICAN PRIVATE SCHOOLS LTD","description":"Contact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\/MM\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel's kindergartenPrimary schoolSecondary schoolNationality: *0 \/ 20School & Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of PreferredContact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\/MM\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel's kindergartenPrimary schoolSecondary schoolNationality: *0 \/ 20School & Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of Preferred Donate blood \u2013 safe a life","canonical_url":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/","robots":"max-image-preview:large","keywords":"donate blood,american academy,american academy (private) primary school,\u03bd\u03ad\u03b1 &amp; \u03b5\u03ba\u03b4\u03b7\u03bb\u03ce\u03c3\u03b5\u03b9\u03c2","webmasterTools":{"google-site-verification":"1GBqZ9YhyEObwKVlJAz6t3iyq0TUQlYqLJq8PYiTPKE","msvalidate.01":"0D6AFA9A4E16BE096B4C1467E7612150","yandex-verification":"f1e4b306a7b5a60d","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/#article","name":"Donate blood \u2013 safe a life | AMERICAN PRIVATE SCHOOLS LTD","headline":"Donate blood &#8211; safe a life","author":{"@id":"https:\/\/americanacademy.ac.cy\/el\/author\/amac\/#author"},"publisher":{"@id":"https:\/\/americanacademy.ac.cy\/el\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/01\/Logo.jpg","@id":"https:\/\/americanacademy.ac.cy\/el\/#articleImage","width":752,"height":813,"caption":"American Academy Logo"},"datePublished":"2025-01-28T20:59:30+02:00","dateModified":"2025-01-28T21:02:07+02:00","inLanguage":"el-EL","mainEntityOfPage":{"@id":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/#webpage"},"isPartOf":{"@id":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/#webpage"},"articleSection":"\u039d\u03ad\u03b1 &amp; \u0395\u03ba\u03b4\u03b7\u03bb\u03ce\u03c3\u03b5\u03b9\u03c2, American Academy, American Academy (Private) Primary School, donate blood, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/el\/#listItem","position":1,"name":"Home","item":"https:\/\/americanacademy.ac.cy\/el\/","nextItem":{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/el\/category\/%ce%bd%ce%ad%ce%b1\/#listItem","name":"\u039d\u03ad\u03b1 &amp; \u0395\u03ba\u03b4\u03b7\u03bb\u03ce\u03c3\u03b5\u03b9\u03c2"}},{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/el\/category\/%ce%bd%ce%ad%ce%b1\/#listItem","position":2,"name":"\u039d\u03ad\u03b1 &amp; \u0395\u03ba\u03b4\u03b7\u03bb\u03ce\u03c3\u03b5\u03b9\u03c2","item":"https:\/\/americanacademy.ac.cy\/el\/category\/%ce%bd%ce%ad%ce%b1\/","nextItem":{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/#listItem","name":"Donate blood &#8211; safe a life"},"previousItem":{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/el\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/#listItem","position":3,"name":"Donate blood &#8211; safe a life","previousItem":{"@type":"ListItem","@id":"https:\/\/americanacademy.ac.cy\/el\/category\/%ce%bd%ce%ad%ce%b1\/#listItem","name":"\u039d\u03ad\u03b1 &amp; \u0395\u03ba\u03b4\u03b7\u03bb\u03ce\u03c3\u03b5\u03b9\u03c2"}}]},{"@type":"Organization","@id":"https:\/\/americanacademy.ac.cy\/el\/#organization","name":"American Academy Limassol","description":"AMERICAN PRIVATE SCHOOLS\u00a0LTD","url":"https:\/\/americanacademy.ac.cy\/el\/","telephone":"+35725337054","logo":{"@type":"ImageObject","url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/01\/Logo.jpg","@id":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/#organizationLogo","width":752,"height":813,"caption":"American Academy Logo"},"image":{"@id":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/American-Academy-Athletic-School-107035131005337","https:\/\/www.instagram.com\/americanacademyprivate\/","https:\/\/www.youtube.com\/channel\/UCgEJukzLPVITvwtccVN0N3w","https:\/\/www.linkedin.com\/company\/american-academy-school\/"]},{"@type":"Person","@id":"https:\/\/americanacademy.ac.cy\/el\/author\/amac\/#author","url":"https:\/\/americanacademy.ac.cy\/el\/author\/amac\/","name":"American Academy"},{"@type":"WebPage","@id":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/#webpage","url":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/","name":"Donate blood \u2013 safe a life | AMERICAN PRIVATE SCHOOLS LTD","description":"Contact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\/MM\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel's kindergartenPrimary schoolSecondary schoolNationality: *0 \/ 20School & Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of PreferredContact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\/MM\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel's kindergartenPrimary schoolSecondary schoolNationality: *0 \/ 20School & Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of Preferred Donate blood \u2013 safe a life","inLanguage":"el-EL","isPartOf":{"@id":"https:\/\/americanacademy.ac.cy\/el\/#website"},"breadcrumb":{"@id":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/#breadcrumblist"},"author":{"@id":"https:\/\/americanacademy.ac.cy\/el\/author\/amac\/#author"},"creator":{"@id":"https:\/\/americanacademy.ac.cy\/el\/author\/amac\/#author"},"datePublished":"2025-01-28T20:59:30+02:00","dateModified":"2025-01-28T21:02:07+02:00"},{"@type":"WebSite","@id":"https:\/\/americanacademy.ac.cy\/el\/#website","url":"https:\/\/americanacademy.ac.cy\/el\/","name":"American Academy Limassol","description":"AMERICAN PRIVATE SCHOOLS\u00a0LTD","inLanguage":"el-EL","publisher":{"@id":"https:\/\/americanacademy.ac.cy\/el\/#organization"}}]},"og:locale":"en_US","og:site_name":"AMERICAN PRIVATE SCHOOLS\u00a0LTD \u2022 AMERICAN PRIVATE SCHOOLS\u00a0LTD","og:type":"article","og:title":"Donate blood \u2013 safe a life | AMERICAN PRIVATE SCHOOLS LTD","og:description":"Contact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\/MM\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel's kindergartenPrimary schoolSecondary schoolNationality: *0 \/ 20School &amp; Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of PreferredContact us Parent First Name: *Parent Last Name: *Student First Name: *Student Last Name: *Student Date of Birth (DD\/MM\/YY): *DaySelect day12345678910111213141516171819202122232425262728293031MonthSelect month123456789101112YearSelect Year212621252124212321222121212021192118211721162115211421132112211121102109210821072106210521042103210221012100209920982097209620952094209320922091209020892088208720862085208420832082208120802079207820772076207520742073207220712070206920682067206620652064206320622061206020592058205720562055205420532052205120502049204820472046204520442043204220412040203920382037203620352034203320322031203020292028202720262025202420232022202120202019201820172016201520142013201220112010200920082007200620052004200320022001200019991998199719961995199419931992199119901989198819871986198519841983198219811980197919781977197619751974197319721971197019691968196719661965196419631962196119601959195819571956195519541953195219511950194919481947194619451944194319421941194019391938193719361935193419331932193119301929192819271926Gender :MaleFemaleSelect your interest *Angel's kindergartenPrimary schoolSecondary schoolNationality: *0 \/ 20School &amp; Class of Interest: *Please select an optionKindergarden 2-5 yoPrimary 5-12 yoSecoundary 12-18 yoGreek School 12-18 yoBoarding School 12-18 yoDates of Preferred Donate blood \u2013 safe a life","og:url":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/","og:image":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/09\/Logo.jpg","og:image:secure_url":"https:\/\/americanacademy.ac.cy\/wp-content\/uploads\/2021\/09\/Logo.jpg","og:image:width":752,"og:image:height":813,"article:published_time":"2025-01-28T18:59:30+00:00","article:modified_time":"2025-01-28T19:02:07+00:00","article:publisher":"https:\/\/www.facebook.com\/American-Academy-Athletic-School-107035131005337"},"aioseo_meta_data":{"post_id":"32977","title":null,"description":null,"keywords":[{"label":"donate blood","value":"donate blood"},{"label":"American Academy","value":"American Academy"},{"label":"American Academy (Private) Primary School","value":"American Academy (Private) Primary School"}],"keyphrases":{"focus":{"keyphrase":"donate blood","score":64,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[],"keywordDensity":{"type":"high","score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-01-28 19:02:06","updated":"2025-06-25 08:33:28","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/americanacademy.ac.cy\/el\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/americanacademy.ac.cy\/el\/category\/%ce%bd%ce%ad%ce%b1\/\" title=\"\u039d\u03ad\u03b1 &amp; \u0395\u03ba\u03b4\u03b7\u03bb\u03ce\u03c3\u03b5\u03b9\u03c2\">\u039d\u03ad\u03b1 &amp; \u0395\u03ba\u03b4\u03b7\u03bb\u03ce\u03c3\u03b5\u03b9\u03c2<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDonate blood \u2013 safe a life\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/americanacademy.ac.cy\/el\/"},{"label":"\u039d\u03ad\u03b1 &amp; \u0395\u03ba\u03b4\u03b7\u03bb\u03ce\u03c3\u03b5\u03b9\u03c2","link":"https:\/\/americanacademy.ac.cy\/el\/category\/%ce%bd%ce%ad%ce%b1\/"},{"label":"Donate blood &#8211; safe a life","link":"https:\/\/americanacademy.ac.cy\/el\/donate-blood-safe-a-life\/"}],"_links":{"self":[{"href":"https:\/\/americanacademy.ac.cy\/el\/wp-json\/wp\/v2\/posts\/32977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/americanacademy.ac.cy\/el\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/americanacademy.ac.cy\/el\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/americanacademy.ac.cy\/el\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/americanacademy.ac.cy\/el\/wp-json\/wp\/v2\/comments?post=32977"}],"version-history":[{"count":2,"href":"https:\/\/americanacademy.ac.cy\/el\/wp-json\/wp\/v2\/posts\/32977\/revisions"}],"predecessor-version":[{"id":32986,"href":"https:\/\/americanacademy.ac.cy\/el\/wp-json\/wp\/v2\/posts\/32977\/revisions\/32986"}],"wp:attachment":[{"href":"https:\/\/americanacademy.ac.cy\/el\/wp-json\/wp\/v2\/media?parent=32977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/americanacademy.ac.cy\/el\/wp-json\/wp\/v2\/categories?post=32977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/americanacademy.ac.cy\/el\/wp-json\/wp\/v2\/tags?post=32977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}